{"id":5261,"date":"2024-08-04T23:21:36","date_gmt":"2024-08-04T21:21:36","guid":{"rendered":"https:\/\/etats-unis.diplomatie.gov.bf\/?p=5261"},"modified":"2025-01-06T23:36:40","modified_gmt":"2025-01-06T22:36:40","slug":"programme-yali-2024-la-delegation-burkinabe-socialise-avec-certains-compatriotes-vivant-dans-la-region-de-washington","status":"publish","type":"post","link":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/programme-yali-2024-la-delegation-burkinabe-socialise-avec-certains-compatriotes-vivant-dans-la-region-de-washington\/","title":{"rendered":"Programme YALI 2024: la d\u00e9l\u00e9gation Burkinab\u00e8 socialise avec certains compatriotes vivant dans la r\u00e9gion de Washington"},"content":{"rendered":"<p>Les 11 jeunes burkinab\u00e8 venus dans le cadre du programme YALI aux USA ont rencontr\u00e9 des membres du Conseil d\u2019Orientation et du Bureau de l\u2019Association des Burkinab\u00e8 de la R\u00e9gion de Washington (ABURWA), ce jeudi 1 er aout 2024. C\u2019\u00e9tait autour d\u2019une sympathique soir\u00e9e \u00e0 Silver Spring dans le Maryland.<\/p>\n<p>Cette soir\u00e9e a \u00e9t\u00e9 une belle occasion pour nos compatriotes de partager avec ces jeunes leaders des exp\u00e9riences de vie sociale et professionnelle utiles pour la suite de leurs carri\u00e8res respectives.<\/p>\n<p>Selon M. Issa DIANDA (membre du Conseil d\u2019Orientation de l\u2019ABURWA), qui recevait la d\u00e9l\u00e9gation \u00e0 son domicile, \u00ab\u00a0ce genre de rencontres est le bienvenu et c\u2019est un r\u00e9el plaisir de pouvoir se retrouver entre fr\u00e8res et s\u0153urs et d\u2019\u00e9changer autour des questions relatives \u00e0 la vie de la Nation\u00a0\u00bb. Et le Charg\u00e9 d\u2019Affaires d\u2019ajouter que \u00ab\u00a0de pareils cadres de rencontre sont de v\u00e9ritables opportunit\u00e9s du donner et du recevoir, tout en renfor\u00e7ant notre vivre ensemble et notre productivit\u00e9\u00a0\u00bb.<\/p>\n<p>Ces jeunes ont en effet \u00e9t\u00e9 tr\u00e8s heureux de rencontrer et de faire connaissance avec des burkinab\u00e8 de grande renomm\u00e9e comme le Journaliste Bagassi KOURA de la Voix de l\u2019Am\u00e9rique, Etienne YOLI de US\/AID, Telesphore KABORE de Save the Children, Hortense HEMA de l\u2019\u00e9v\u00e9nement de promotion du Burkina d\u00e9nomm\u00e9\u00a0<em><u>Dassan Daga,<\/u><\/em>\u00a0l\u2019Architecte Anicet DELA et bien d\u2019autres.<\/p>\n<p>Au terme de leur s\u00e9jour, les dignes repr\u00e9sentants du programme YALI, cr\u00e9\u00e9 par le Pr\u00e9sident Barack OBAMA en 2014, regagnent la terre du Burkina, enrichis de nouvelles exp\u00e9riences et \u00ab\u00a0d\u2019une autre fa\u00e7on de voir et d\u2019entreprendre les choses\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les 11 jeunes burkinab\u00e8 venus dans le cadre du programme YALI aux USA ont rencontr\u00e9 des membres du Conseil d\u2019Orientation et du Bureau de l\u2019Association des Burkinab\u00e8 de la R\u00e9gion de Washington (ABURWA), ce jeudi 1 er aout 2024. C\u2019\u00e9tait autour d\u2019une sympathique soir\u00e9e \u00e0 Silver Spring dans le Maryland. Cette soir\u00e9e a \u00e9t\u00e9 une [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-5261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/posts\/5261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/comments?post=5261"}],"version-history":[{"count":1,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/posts\/5261\/revisions"}],"predecessor-version":[{"id":5270,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/posts\/5261\/revisions\/5270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/media\/5269"}],"wp:attachment":[{"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/media?parent=5261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/categories?post=5261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/etats-unis.diplomatie.gov.bf\/index.php\/wp-json\/wp\/v2\/tags?post=5261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}